{"id":3514,"date":"2020-01-09T19:15:37","date_gmt":"2020-01-10T00:15:37","guid":{"rendered":"https:\/\/opemisca.com\/blog\/?p=3514"},"modified":"2020-01-09T19:15:37","modified_gmt":"2020-01-10T00:15:37","slug":"5-tactiques-hivernale-pour-dore-difficile","status":"publish","type":"post","link":"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/","title":{"rendered":"5 Tactiques hivernale pour dor\u00e9 difficile!!"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3525\" data-permalink=\"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/charles-antoine\/\" data-orig-file=\"https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2020\/01\/charles-antoine.jpg?fit=360%2C480&amp;ssl=1\" data-orig-size=\"360,480\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"charles antoine\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2020\/01\/charles-antoine.jpg?fit=225%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2020\/01\/charles-antoine.jpg?fit=360%2C480&amp;ssl=1\" class=\"size-medium wp-image-3525 aligncenter\" src=\"https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2020\/01\/charles-antoine.jpg?resize=225%2C300&#038;ssl=1\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2020\/01\/charles-antoine.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2020\/01\/charles-antoine.jpg?w=360&amp;ssl=1 360w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/p>\n<h6 style=\"text-align: center;\">Charles-Antoine Brassard un de nos collaborateurs posant fi\u00e8rement avec une superbe p\u00eache<\/h6>\n<p>&nbsp;<\/p>\n<p>Contrairement \u00e0 ce que bon nombre de p\u00eacheurs croient le dor\u00e9 ne tombe pas inactif ou paresseux l&rsquo;hiver, je crois que cette croyance vient plus du manque de succ\u00e8s de certain p\u00eacheur que d&rsquo;un fait r\u00e9el. Je ne ferai pas une grande r\u00e9v\u00e9lation an affirmant que le grand secret du succ\u00e8s dans la p\u00eache hivernale \u00e0 nos percid\u00e9s favoris ne rel\u00e8ve pas de la chance pur et simple mais bien de sa localisation.<\/p>\n<p>1 &#8211; Si on pense localisation, en d\u00e9but de saison hivernale vous retrouverez les dor\u00e9s tout pr\u00eat des endroits ou il \u00e9taient pr\u00e9sent en automne; sois pr\u00eat des hauts fond avec un acc\u00e8s rapide \u00e0 l&rsquo;eau plus profonde; plus la saison avance plus vos proies gagneront l&rsquo;eau plus chaude des profondeurs. Il vous sera donc tr\u00e8s payant de rechercher les butons dansles zones un peu plus profonde du secteur; ces derniers pourraient cacher un bon rassemblement de dor\u00e9. En fin de saison la p\u00e9riode de fraie se faisant de plus en plus imminente ces derniers se rapprocheront donc de ceux ci; vous aurez donc avantage \u00e0 p\u00eacher les embouchures de rivi\u00e8res, les fond graveleux. Il vous sera payant de garder en t\u00eate que vos dor\u00e9s ont besoin d&rsquo;une zone de repos et d&rsquo;un aire d&rsquo;alimentation relativement rapproch\u00e9 l&rsquo;un de l&rsquo;autre.<\/p>\n<p>2 &#8211; Aussi simple que cela puisse parraitre il vous sera tr\u00e8s avantageux de percer plusieurs trou \u00e0 l&rsquo;endroit ou devraient se trouver vos <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1202\" data-permalink=\"https:\/\/opemisca.com\/blog\/?attachment_id=1202\" data-orig-file=\"https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2018\/08\/dor%C3%A9bubble.jpg?fit=720%2C960&amp;ssl=1\" data-orig-size=\"720,960\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"dor\u00e9bubble\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2018\/08\/dor%C3%A9bubble.jpg?fit=225%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2018\/08\/dor%C3%A9bubble.jpg?fit=720%2C960&amp;ssl=1\" class=\"size-medium wp-image-1202 alignright\" src=\"https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2018\/08\/dor%C3%A9bubble.jpg?resize=225%2C300&#038;ssl=1\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2018\/08\/dor%C3%A9bubble.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2018\/08\/dor%C3%A9bubble.jpg?resize=416%2C555&amp;ssl=1 416w, https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2018\/08\/dor%C3%A9bubble.jpg?w=720&amp;ssl=1 720w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/>poissons. Vous pourrez ainsi alterner la dandinette quelques minutes par trou afin de trouver la pr\u00e9sentation et l&rsquo;angle id\u00e9al qui provoquera l&rsquo;attaque esp\u00e9r\u00e9e.<\/p>\n<p>3 &#8211; Utilisez la technologie \u00e0 votre port\u00e9e; que ce sois une cam\u00e9ra sous-marine, un \u00e9chosondeur ou encore un flasheur ces appareils vous permettrons premi\u00e8rement de valider la pr\u00e9sence de poisson, mais encore plus important d&rsquo;analyser leur r\u00e9actions \u00e0 vos pr\u00e9sentations et \u00e0 vos actions. Ce qui vous dictera quel approche utiliser \u00e0 quel moment de la journ\u00e9e\/saison.<\/p>\n<p>4 &#8211; Le choix du leurre et la pr\u00e9sentation est de la plus grande importance; puisque c&rsquo;est ce que le dor\u00e9 aura devant lui pour l&rsquo;inciter \u00e0 mordre ou pas. Les leurres \u00e9m\u00e9tant des vibrations intense comme par exemple nos\u00a0<a href=\"https:\/\/opemisca.com\/blog\/produit\/bubble-blade\/\" target=\"_blank\" rel=\"noopener noreferrer\">Bubble blade<\/a> sont d&rsquo;une efficacit\u00e9 redoutable, les leurres \u00ab\u00a0Glow in the dark\u00a0\u00bb comme nos\u00a0<a href=\"https:\/\/opemisca.com\/blog\/produit\/mini-bubble-eyes-1oz\/\" target=\"_blank\" rel=\"noopener noreferrer\">Bubble Eyes<\/a> \u00a0sont aussi un atout majeur dans votre coffre; les poissons nageur sans bavette sont aussi tr\u00e8s productif. Si la r\u00e9glementation de la zone dans laquelle vous p\u00eacher le permet l&rsquo;ajout d&rsquo;une t\u00eate de m\u00e9n\u00e9 sur le tr\u00e9pied est une excellente id\u00e9e; sinon un vers de terre ou un asticot fera l&rsquo;affaire. N&rsquo;oubliez pas que le dor\u00e9 attaque principalement proche du fond, vous pr\u00e9senterez donc votre leurre en fonction de ce fait.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3526\" data-permalink=\"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/dore1\/\" data-orig-file=\"https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2020\/01\/dor%C3%A91.jpg?fit=2048%2C1536&amp;ssl=1\" data-orig-size=\"2048,1536\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"dor\u00e91\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2020\/01\/dor%C3%A91.jpg?fit=300%2C225&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2020\/01\/dor%C3%A91.jpg?fit=980%2C735&amp;ssl=1\" class=\"size-medium wp-image-3526 alignleft\" src=\"https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2020\/01\/dor%C3%A91.jpg?resize=300%2C225&#038;ssl=1\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2020\/01\/dor%C3%A91.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2020\/01\/dor%C3%A91.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2020\/01\/dor%C3%A91.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2020\/01\/dor%C3%A91.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2020\/01\/dor%C3%A91.jpg?resize=1320%2C990&amp;ssl=1 1320w, https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2020\/01\/dor%C3%A91.jpg?resize=416%2C312&amp;ssl=1 416w, https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2020\/01\/dor%C3%A91.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2020\/01\/dor%C3%A91.jpg?w=1960&amp;ssl=1 1960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>5 &#8211; Si votre occupation du temps vous le permet vous devriez p\u00eacher plusieurs p\u00e9riode diff\u00e9rente de la journ\u00e9e. Comme plusieurs le savent la p\u00eache au dor\u00e9 est g\u00e9n\u00e9ralement plus productive une heure avant et une heure apr\u00e8s le lever et le coucher du soleil; toutefois ce n&rsquo;est pas une r\u00e8gle immuable vous pourriez en tirer profit \u00e0 p\u00eacher des p\u00e9riodes diff\u00e9rentes de la journ\u00e9e, tout en analysant la nebulosit\u00e9, la pression, le vent etc&#8230; afin de vous faire une id\u00e9e de comment r\u00e9agiront vos dor\u00e9s \u00e0 ces facteurs m\u00e9t\u00e9o.<\/p>\n<p>Bien sur cet article ne vous donne que des indications g\u00e9n\u00e9rales, par contre lors de vos prochaines sorties essayez de vous en souvenir cela pourrait augmenter significativement votre moyenne au baton. Sur ce bonne p\u00eache et soyez prudent.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Charles-Antoine Brassard un de nos collaborateurs posant fi\u00e8rement avec une superbe p\u00eache &nbsp; Contrairement \u00e0 ce que bon nombre de p\u00eacheurs croient le dor\u00e9 ne tombe pas inactif ou paresseux l&rsquo;hiver, je crois que cette croyance vient plus du manque de succ\u00e8s de certain p\u00eacheur que d&rsquo;un fait r\u00e9el. Je ne ferai pas une grande [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7,6],"tags":[],"class_list":["post-3514","post","type-post","status-publish","format-standard","hentry","category-equipement","category-technique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>5 Tactiques hivernale pour dor\u00e9 difficile!! - Les Leurres Op\u00e9misca<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 Tactiques hivernale pour dor\u00e9 difficile!! - Les Leurres Op\u00e9misca\" \/>\n<meta property=\"og:description\" content=\"Charles-Antoine Brassard un de nos collaborateurs posant fi\u00e8rement avec une superbe p\u00eache &nbsp; Contrairement \u00e0 ce que bon nombre de p\u00eacheurs croient le dor\u00e9 ne tombe pas inactif ou paresseux l&rsquo;hiver, je crois que cette croyance vient plus du manque de succ\u00e8s de certain p\u00eacheur que d&rsquo;un fait r\u00e9el. Je ne ferai pas une grande [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/\" \/>\n<meta property=\"og:site_name\" content=\"Les Leurres Op\u00e9misca\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lesleurresopemisca\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-10T00:15:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/opemisca.com\/blog\/wp-content\/uploads\/2020\/01\/charles-antoine-225x300.jpg\" \/>\n<meta name=\"author\" content=\"Pierre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/\"},\"author\":{\"name\":\"Pierre\",\"@id\":\"https:\/\/opemisca.com\/blog\/#\/schema\/person\/86e5ef84ee093f8929f1d09776e46259\"},\"headline\":\"5 Tactiques hivernale pour dor\u00e9 difficile!!\",\"datePublished\":\"2020-01-10T00:15:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/\"},\"wordCount\":663,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/opemisca.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/opemisca.com\/blog\/wp-content\/uploads\/2020\/01\/charles-antoine-225x300.jpg\",\"articleSection\":[\"\u00c9quipement\",\"Technique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/\",\"url\":\"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/\",\"name\":\"5 Tactiques hivernale pour dor\u00e9 difficile!! - Les Leurres Op\u00e9misca\",\"isPartOf\":{\"@id\":\"https:\/\/opemisca.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/opemisca.com\/blog\/wp-content\/uploads\/2020\/01\/charles-antoine-225x300.jpg\",\"datePublished\":\"2020-01-10T00:15:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2020\/01\/charles-antoine.jpg?fit=360%2C480&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2020\/01\/charles-antoine.jpg?fit=360%2C480&ssl=1\",\"width\":360,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/opemisca.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5 Tactiques hivernale pour dor\u00e9 difficile!!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/opemisca.com\/blog\/#website\",\"url\":\"https:\/\/opemisca.com\/blog\/\",\"name\":\"Les Leurres Op\u00e9misca\",\"description\":\"Passionn\u00e9 de p\u00eache sportive\",\"publisher\":{\"@id\":\"https:\/\/opemisca.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/opemisca.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/opemisca.com\/blog\/#organization\",\"name\":\"Les Leurres Op\u00e9misca\",\"url\":\"https:\/\/opemisca.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/opemisca.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2018\/07\/logosharp.png?fit=357%2C213&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2018\/07\/logosharp.png?fit=357%2C213&ssl=1\",\"width\":357,\"height\":213,\"caption\":\"Les Leurres Op\u00e9misca\"},\"image\":{\"@id\":\"https:\/\/opemisca.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/lesleurresopemisca\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/opemisca.com\/blog\/#\/schema\/person\/86e5ef84ee093f8929f1d09776e46259\",\"name\":\"Pierre\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/opemisca.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c78cd60d03280f3b31c5a57781ef7172d5b4eb7d13cc0dcfeb209e615a750fb5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c78cd60d03280f3b31c5a57781ef7172d5b4eb7d13cc0dcfeb209e615a750fb5?s=96&d=mm&r=g\",\"caption\":\"Pierre\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5 Tactiques hivernale pour dor\u00e9 difficile!! - Les Leurres Op\u00e9misca","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/","og_locale":"fr_FR","og_type":"article","og_title":"5 Tactiques hivernale pour dor\u00e9 difficile!! - Les Leurres Op\u00e9misca","og_description":"Charles-Antoine Brassard un de nos collaborateurs posant fi\u00e8rement avec une superbe p\u00eache &nbsp; Contrairement \u00e0 ce que bon nombre de p\u00eacheurs croient le dor\u00e9 ne tombe pas inactif ou paresseux l&rsquo;hiver, je crois que cette croyance vient plus du manque de succ\u00e8s de certain p\u00eacheur que d&rsquo;un fait r\u00e9el. Je ne ferai pas une grande [&hellip;]","og_url":"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/","og_site_name":"Les Leurres Op\u00e9misca","article_publisher":"https:\/\/www.facebook.com\/lesleurresopemisca\/","article_published_time":"2020-01-10T00:15:37+00:00","og_image":[{"url":"https:\/\/opemisca.com\/blog\/wp-content\/uploads\/2020\/01\/charles-antoine-225x300.jpg","type":"","width":"","height":""}],"author":"Pierre","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Pierre","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/#article","isPartOf":{"@id":"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/"},"author":{"name":"Pierre","@id":"https:\/\/opemisca.com\/blog\/#\/schema\/person\/86e5ef84ee093f8929f1d09776e46259"},"headline":"5 Tactiques hivernale pour dor\u00e9 difficile!!","datePublished":"2020-01-10T00:15:37+00:00","mainEntityOfPage":{"@id":"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/"},"wordCount":663,"commentCount":1,"publisher":{"@id":"https:\/\/opemisca.com\/blog\/#organization"},"image":{"@id":"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/#primaryimage"},"thumbnailUrl":"https:\/\/opemisca.com\/blog\/wp-content\/uploads\/2020\/01\/charles-antoine-225x300.jpg","articleSection":["\u00c9quipement","Technique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/","url":"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/","name":"5 Tactiques hivernale pour dor\u00e9 difficile!! - Les Leurres Op\u00e9misca","isPartOf":{"@id":"https:\/\/opemisca.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/#primaryimage"},"image":{"@id":"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/#primaryimage"},"thumbnailUrl":"https:\/\/opemisca.com\/blog\/wp-content\/uploads\/2020\/01\/charles-antoine-225x300.jpg","datePublished":"2020-01-10T00:15:37+00:00","breadcrumb":{"@id":"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/#primaryimage","url":"https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2020\/01\/charles-antoine.jpg?fit=360%2C480&ssl=1","contentUrl":"https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2020\/01\/charles-antoine.jpg?fit=360%2C480&ssl=1","width":360,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/opemisca.com\/blog\/2020\/01\/09\/5-tactiques-hivernale-pour-dore-difficile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/opemisca.com\/blog\/"},{"@type":"ListItem","position":2,"name":"5 Tactiques hivernale pour dor\u00e9 difficile!!"}]},{"@type":"WebSite","@id":"https:\/\/opemisca.com\/blog\/#website","url":"https:\/\/opemisca.com\/blog\/","name":"Les Leurres Op\u00e9misca","description":"Passionn\u00e9 de p\u00eache sportive","publisher":{"@id":"https:\/\/opemisca.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/opemisca.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/opemisca.com\/blog\/#organization","name":"Les Leurres Op\u00e9misca","url":"https:\/\/opemisca.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/opemisca.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2018\/07\/logosharp.png?fit=357%2C213&ssl=1","contentUrl":"https:\/\/i0.wp.com\/opemisca.com\/blog\/wp-content\/uploads\/2018\/07\/logosharp.png?fit=357%2C213&ssl=1","width":357,"height":213,"caption":"Les Leurres Op\u00e9misca"},"image":{"@id":"https:\/\/opemisca.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lesleurresopemisca\/"]},{"@type":"Person","@id":"https:\/\/opemisca.com\/blog\/#\/schema\/person\/86e5ef84ee093f8929f1d09776e46259","name":"Pierre","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/opemisca.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c78cd60d03280f3b31c5a57781ef7172d5b4eb7d13cc0dcfeb209e615a750fb5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c78cd60d03280f3b31c5a57781ef7172d5b4eb7d13cc0dcfeb209e615a750fb5?s=96&d=mm&r=g","caption":"Pierre"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9ClBa-UG","jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/opemisca.com\/blog\/wp-json\/wp\/v2\/posts\/3514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/opemisca.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/opemisca.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/opemisca.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/opemisca.com\/blog\/wp-json\/wp\/v2\/comments?post=3514"}],"version-history":[{"count":12,"href":"https:\/\/opemisca.com\/blog\/wp-json\/wp\/v2\/posts\/3514\/revisions"}],"predecessor-version":[{"id":3528,"href":"https:\/\/opemisca.com\/blog\/wp-json\/wp\/v2\/posts\/3514\/revisions\/3528"}],"wp:attachment":[{"href":"https:\/\/opemisca.com\/blog\/wp-json\/wp\/v2\/media?parent=3514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/opemisca.com\/blog\/wp-json\/wp\/v2\/categories?post=3514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/opemisca.com\/blog\/wp-json\/wp\/v2\/tags?post=3514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}